{"id":6802,"date":"2024-02-26T11:00:32","date_gmt":"2024-02-26T14:00:32","guid":{"rendered":"https:\/\/sinqia.com.br\/?p=6802"},"modified":"2024-06-20T16:20:08","modified_gmt":"2024-06-20T19:20:08","slug":"adesao-automatica-previdencia-complementar","status":"publish","type":"post","link":"https:\/\/evertectrends.com\/pt-br\/adesao-automatica-previdencia-complementar\/","title":{"rendered":"Ades\u00e3o autom\u00e1tica na previd\u00eancia complementar: saiba como funciona e o que muda"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">O Conselho Nacional de Previd\u00eancia Complementar (CNPC) aprovou recentemente uma nova resolu\u00e7\u00e3o que permite a <strong>ades\u00e3o autom\u00e1tica na previd\u00eancia complementar.<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Antes, essa possibilidade existia somente nos planos de benef\u00edcios de servidores p\u00fablicos. Mas, agora, com aprova\u00e7\u00e3o da nova resolu\u00e7\u00e3o, trabalhadores do setor p\u00fablico e privado de empresas que oferecem plano de previd\u00eancia complementar poder\u00e3o ser inscritos automaticamente no plano.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Acompanhe conosco essa leitura e veja a seguir como funciona e o que muda com a implementa\u00e7\u00e3o da nova resolu\u00e7\u00e3o aprovada pelo CNPC. Confira!<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">O que \u00e9 a ades\u00e3o autom\u00e1tica na previd\u00eancia complementar?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Em 7 de fevereiro de 2024, o CNPC aprovou por unanimidade a resolu\u00e7\u00e3o que <\/span><b>autoriza a inscri\u00e7\u00e3o autom\u00e1tica de trabalhadores <\/b><span style=\"font-weight: 400;\">na previd\u00eancia complementar.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Desse modo, as empresas que oferecem esse benef\u00edcio aos seus funcion\u00e1rios, poder\u00e3o inscrev\u00ea-los automaticamente no <\/span><a href=\"https:\/\/sinqia.com.br\/2023\/07\/25\/portabilidade-previdencia\/\"><span style=\"font-weight: 400;\">plano de previd\u00eancia fechado<\/span><\/a><span style=\"font-weight: 400;\">. O objetivo com essa iniciativa \u00e9 estimular a participa\u00e7\u00e3o de novos usu\u00e1rios e, assim, fomentar o setor com novos investimentos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mais do que isso, trata-se de uma mudan\u00e7a que torna a ades\u00e3o ao sistema de previd\u00eancia complementar menos burocr\u00e1tica. Al\u00e9m disso, com a inscri\u00e7\u00e3o autom\u00e1tica, o trabalhador ter\u00e1 a oportunidade de conhecer melhor os servi\u00e7os prestados pelas funda\u00e7\u00f5es privadas antes de decidir por sua perman\u00eancia no plano, j\u00e1 que <\/span><b>a ades\u00e3o \u00e9 autom\u00e1tica, mas n\u00e3o obrigat\u00f3ria<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Como funciona<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Basicamente, o sistema funcionar\u00e1 no <\/span><b>esquema de \u201c<\/b><b><i>opt out<\/i><\/b><b>\u201d<\/b><span style=\"font-weight: 400;\">. Ou seja, nele, o benefici\u00e1rio ser\u00e1 inscrito automaticamente no servi\u00e7o por seu empregador. Mas, tamb\u00e9m poder\u00e1 cancelar sua ades\u00e3o mediante manifesta\u00e7\u00e3o expressa de sua vontade.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sendo assim, o trabalhador que tiver sua ades\u00e3o autom\u00e1tica na previd\u00eancia, poder\u00e1 solicitar seu desligamento em at\u00e9 120 dias de sua inscri\u00e7\u00e3o. Al\u00e9m disso, o mesmo tamb\u00e9m ter\u00e1 direito \u00e0 restitui\u00e7\u00e3o dos valores descontados em at\u00e9 60 dias ap\u00f3s sua desist\u00eancia.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Lembrando que esse tipo de ades\u00e3o na previd\u00eancia fechada contemplar\u00e1 empresas cuja contribui\u00e7\u00e3o do empregador seja de, no m\u00ednimo, 20% do valor total de contribui\u00e7\u00e3o previdenci\u00e1ria para o plano de benef\u00edcios.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">O que muda com a ades\u00e3o autom\u00e1tica?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Com a nova resolu\u00e7\u00e3o do CNPC, agora o trabalhador possui duas modalidades de ades\u00e3o aos planos de previd\u00eancia privada, que s\u00e3o:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Ades\u00e3o convencional<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Ades\u00e3o autom\u00e1tica<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Nesse caso, a principal mudan\u00e7a est\u00e1 no uso da ades\u00e3o autom\u00e1tica por todos os tipos de patrocinadores, tanto do setor p\u00fablico, quanto privado. Desse modo, com essa nova sistem\u00e1tica, ser\u00e1 preciso que as funda\u00e7\u00f5es previdenci\u00e1rias incluam a modalidade autom\u00e1tica no seu regulamento. Al\u00e9m disso, cada entidade previdenci\u00e1ria dever\u00e1 definir por qual modalidade optar, bem como tratar de outros pontos envolvendo prazos, formas de desist\u00eancias, entre outras condi\u00e7\u00f5es.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Segundo a nova norma, o trabalhador participante na modalidade convencional ou por <\/span><a href=\"https:\/\/sinqia.com.br\/2024\/02\/21\/adesao-a-previdencia\/\"><span style=\"font-weight: 400;\">ades\u00e3o<\/span><\/a><span style=\"font-weight: 400;\"> autom\u00e1tica na previd\u00eancia complementar, dever\u00e1 ser notificado sobre a possibilidade de cancelamento da sua inscri\u00e7\u00e3o, podendo efetu\u00e1-la desde que ainda n\u00e3o tenha gozado dos benef\u00edcios.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para o CNPC, a aprova\u00e7\u00e3o dessa nova resolu\u00e7\u00e3o <\/span><b>amplia a cobertura previdenci\u00e1ria no setor privado<\/b><span style=\"font-weight: 400;\">, elevando a prote\u00e7\u00e3o social dos trabalhadores e suas fam\u00edlias. Al\u00e9m disso, com essa mudan\u00e7a o Brasil entra em sintonia com as boas pr\u00e1ticas envolvendo pol\u00edticas p\u00fablicas previdenci\u00e1rias j\u00e1 implementadas em v\u00e1rios outros pa\u00edses. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Conselho Nacional de Previd\u00eancia Complementar (CNPC) aprovou recentemente uma nova resolu\u00e7\u00e3o que permite a ades\u00e3o autom\u00e1tica na previd\u00eancia complementar. Antes, essa possibilidade existia somente nos planos de benef\u00edcios de servidores p\u00fablicos. Mas, agora, com aprova\u00e7\u00e3o da nova resolu\u00e7\u00e3o, trabalhadores do setor p\u00fablico e privado de empresas que oferecem plano de previd\u00eancia complementar poder\u00e3o ser [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":49921,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[997],"tags":[350,954,957,538],"class_list":["post-6802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regulamentacao","tag-previdencia","tag-previdencia-complementar","tag-resolucao","tag-sinqia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ades\u00e3o autom\u00e1tica na previd\u00eancia complementar: saiba como funciona e o que muda - Evertec Trends<\/title>\n<meta name=\"description\" content=\"Entenda como funciona a ades\u00e3o autom\u00e1tica na previd\u00eancia complementar e o que muda com a implementa\u00e7\u00e3o da nova resolu\u00e7\u00e3o aprovada pelo CNPC.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/adesao-automatica-previdencia-complementar\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ades\u00e3o autom\u00e1tica na previd\u00eancia complementar: saiba como funciona e o que muda - Evertec Trends\" \/>\n<meta property=\"og:description\" content=\"Entenda como funciona a ades\u00e3o autom\u00e1tica na previd\u00eancia complementar e o que muda com a implementa\u00e7\u00e3o da nova resolu\u00e7\u00e3o aprovada pelo CNPC.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/adesao-automatica-previdencia-complementar\/\" \/>\n<meta property=\"og:site_name\" content=\"Evertec Trends\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-26T14:00:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-20T19:20:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/evertectrends.dev.creativetm.co\/wp-content\/uploads\/2024\/05\/Adesao-Automatica.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Evertec Trends\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Evertec Trends\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/adesao-automatica-previdencia-complementar\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/adesao-automatica-previdencia-complementar\/\"},\"author\":{\"name\":\"Evertec Trends\",\"@id\":\"https:\/\/evertectrends.com\/#\/schema\/person\/e1ebcb37c3e82c62bf694bb1eca91f4d\"},\"headline\":\"Ades\u00e3o autom\u00e1tica na previd\u00eancia complementar: saiba como funciona e o que muda\",\"datePublished\":\"2024-02-26T14:00:32+00:00\",\"dateModified\":\"2024-06-20T19:20:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/adesao-automatica-previdencia-complementar\/\"},\"wordCount\":613,\"publisher\":{\"@id\":\"https:\/\/evertectrends.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/adesao-automatica-previdencia-complementar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2024\/05\/Adesao-Automatica.png\",\"keywords\":[\"Previd\u00eancia\",\"Previd\u00eancia Complementar\",\"Resolu\u00e7\u00e3o\",\"sinqia\"],\"articleSection\":[\"Regulamenta\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/adesao-automatica-previdencia-complementar\/\",\"url\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/adesao-automatica-previdencia-complementar\/\",\"name\":\"Ades\u00e3o autom\u00e1tica na previd\u00eancia complementar: saiba como funciona e o que muda - Evertec Trends\",\"isPartOf\":{\"@id\":\"https:\/\/evertectrends.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/adesao-automatica-previdencia-complementar\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/adesao-automatica-previdencia-complementar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2024\/05\/Adesao-Automatica.png\",\"datePublished\":\"2024-02-26T14:00:32+00:00\",\"dateModified\":\"2024-06-20T19:20:08+00:00\",\"description\":\"Entenda como funciona a ades\u00e3o autom\u00e1tica na previd\u00eancia complementar e o que muda com a implementa\u00e7\u00e3o da nova resolu\u00e7\u00e3o aprovada pelo CNPC.\",\"breadcrumb\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/adesao-automatica-previdencia-complementar\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/adesao-automatica-previdencia-complementar\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/adesao-automatica-previdencia-complementar\/#primaryimage\",\"url\":\"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2024\/05\/Adesao-Automatica.png\",\"contentUrl\":\"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2024\/05\/Adesao-Automatica.png\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/adesao-automatica-previdencia-complementar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/evertectrends.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Regulamenta\u00e7\u00e3o\",\"item\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/categoria\/regulamentacao\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ades\u00e3o autom\u00e1tica na previd\u00eancia complementar: saiba como funciona e o que muda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/evertectrends.com\/#website\",\"url\":\"https:\/\/evertectrends.com\/\",\"name\":\"Evertec Trends\",\"description\":\"As tend\u00eancias de tecnologia para inovar com estrat\u00e9gia\",\"publisher\":{\"@id\":\"https:\/\/evertectrends.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/evertectrends.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/evertectrends.com\/#organization\",\"name\":\"Evertec Trends\",\"url\":\"https:\/\/evertectrends.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/evertectrends.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2024\/03\/logotipo-evertec-trends.svg\",\"contentUrl\":\"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2024\/03\/logotipo-evertec-trends.svg\",\"width\":241,\"height\":29,\"caption\":\"Evertec Trends\"},\"image\":{\"@id\":\"https:\/\/evertectrends.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/evertectrends.com\/#\/schema\/person\/e1ebcb37c3e82c62bf694bb1eca91f4d\",\"name\":\"Evertec Trends\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/evertectrends.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f46217c56c100deb166f67953efa3f81077701bca98a102e48544095d631803d?s=96&d=robohash&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f46217c56c100deb166f67953efa3f81077701bca98a102e48544095d631803d?s=96&d=robohash&r=g\",\"caption\":\"Evertec Trends\"},\"description\":\"Mais que um portal de conte\u00fados, um ponto de encontro para quem quer desvendar o setor financeiro.\",\"sameAs\":[\"https:\/\/www.instagram.com\/evertecinc\",\"https:\/\/www.linkedin.com\/company\/evertec\/\"],\"url\":\"https:\/\/evertectrends.com\/pt-br\/author\/evertectrends\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ades\u00e3o autom\u00e1tica na previd\u00eancia complementar: saiba como funciona e o que muda - Evertec Trends","description":"Entenda como funciona a ades\u00e3o autom\u00e1tica na previd\u00eancia complementar e o que muda com a implementa\u00e7\u00e3o da nova resolu\u00e7\u00e3o aprovada pelo CNPC.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/adesao-automatica-previdencia-complementar\/","og_locale":"pt_BR","og_type":"article","og_title":"Ades\u00e3o autom\u00e1tica na previd\u00eancia complementar: saiba como funciona e o que muda - Evertec Trends","og_description":"Entenda como funciona a ades\u00e3o autom\u00e1tica na previd\u00eancia complementar e o que muda com a implementa\u00e7\u00e3o da nova resolu\u00e7\u00e3o aprovada pelo CNPC.","og_url":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/adesao-automatica-previdencia-complementar\/","og_site_name":"Evertec Trends","article_published_time":"2024-02-26T14:00:32+00:00","article_modified_time":"2024-06-20T19:20:08+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/evertectrends.dev.creativetm.co\/wp-content\/uploads\/2024\/05\/Adesao-Automatica.png","type":"image\/png"}],"author":"Evertec Trends","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Evertec Trends","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/adesao-automatica-previdencia-complementar\/#article","isPartOf":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/adesao-automatica-previdencia-complementar\/"},"author":{"name":"Evertec Trends","@id":"https:\/\/evertectrends.com\/#\/schema\/person\/e1ebcb37c3e82c62bf694bb1eca91f4d"},"headline":"Ades\u00e3o autom\u00e1tica na previd\u00eancia complementar: saiba como funciona e o que muda","datePublished":"2024-02-26T14:00:32+00:00","dateModified":"2024-06-20T19:20:08+00:00","mainEntityOfPage":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/adesao-automatica-previdencia-complementar\/"},"wordCount":613,"publisher":{"@id":"https:\/\/evertectrends.com\/#organization"},"image":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/adesao-automatica-previdencia-complementar\/#primaryimage"},"thumbnailUrl":"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2024\/05\/Adesao-Automatica.png","keywords":["Previd\u00eancia","Previd\u00eancia Complementar","Resolu\u00e7\u00e3o","sinqia"],"articleSection":["Regulamenta\u00e7\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/adesao-automatica-previdencia-complementar\/","url":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/adesao-automatica-previdencia-complementar\/","name":"Ades\u00e3o autom\u00e1tica na previd\u00eancia complementar: saiba como funciona e o que muda - Evertec Trends","isPartOf":{"@id":"https:\/\/evertectrends.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/adesao-automatica-previdencia-complementar\/#primaryimage"},"image":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/adesao-automatica-previdencia-complementar\/#primaryimage"},"thumbnailUrl":"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2024\/05\/Adesao-Automatica.png","datePublished":"2024-02-26T14:00:32+00:00","dateModified":"2024-06-20T19:20:08+00:00","description":"Entenda como funciona a ades\u00e3o autom\u00e1tica na previd\u00eancia complementar e o que muda com a implementa\u00e7\u00e3o da nova resolu\u00e7\u00e3o aprovada pelo CNPC.","breadcrumb":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/adesao-automatica-previdencia-complementar\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/evertectrends.dev.creativetm.co\/pt-br\/adesao-automatica-previdencia-complementar\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/adesao-automatica-previdencia-complementar\/#primaryimage","url":"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2024\/05\/Adesao-Automatica.png","contentUrl":"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2024\/05\/Adesao-Automatica.png","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/adesao-automatica-previdencia-complementar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/evertectrends.com\/"},{"@type":"ListItem","position":2,"name":"Regulamenta\u00e7\u00e3o","item":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/categoria\/regulamentacao\/"},{"@type":"ListItem","position":3,"name":"Ades\u00e3o autom\u00e1tica na previd\u00eancia complementar: saiba como funciona e o que muda"}]},{"@type":"WebSite","@id":"https:\/\/evertectrends.com\/#website","url":"https:\/\/evertectrends.com\/","name":"Evertec Trends","description":"As tend\u00eancias de tecnologia para inovar com estrat\u00e9gia","publisher":{"@id":"https:\/\/evertectrends.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/evertectrends.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/evertectrends.com\/#organization","name":"Evertec Trends","url":"https:\/\/evertectrends.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/evertectrends.com\/#\/schema\/logo\/image\/","url":"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2024\/03\/logotipo-evertec-trends.svg","contentUrl":"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2024\/03\/logotipo-evertec-trends.svg","width":241,"height":29,"caption":"Evertec Trends"},"image":{"@id":"https:\/\/evertectrends.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/evertectrends.com\/#\/schema\/person\/e1ebcb37c3e82c62bf694bb1eca91f4d","name":"Evertec Trends","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/evertectrends.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f46217c56c100deb166f67953efa3f81077701bca98a102e48544095d631803d?s=96&d=robohash&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f46217c56c100deb166f67953efa3f81077701bca98a102e48544095d631803d?s=96&d=robohash&r=g","caption":"Evertec Trends"},"description":"Mais que um portal de conte\u00fados, um ponto de encontro para quem quer desvendar o setor financeiro.","sameAs":["https:\/\/www.instagram.com\/evertecinc","https:\/\/www.linkedin.com\/company\/evertec\/"],"url":"https:\/\/evertectrends.com\/pt-br\/author\/evertectrends\/"}]}},"featured_image_url":"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2024\/05\/Adesao-Automatica.png","primary_category":"Regulamenta\u00e7\u00e3o","_links":{"self":[{"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/posts\/6802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/comments?post=6802"}],"version-history":[{"count":0,"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/posts\/6802\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/media\/49921"}],"wp:attachment":[{"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/media?parent=6802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/categories?post=6802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/tags?post=6802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}