{"id":55141,"date":"2025-01-29T07:00:00","date_gmt":"2025-01-29T10:00:00","guid":{"rendered":"https:\/\/evertectrends.com\/?p=55141"},"modified":"2025-08-19T11:47:28","modified_gmt":"2025-08-19T14:47:28","slug":"lei-de-fintech-principais-desafios-para-2025","status":"publish","type":"post","link":"https:\/\/evertectrends.com\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/","title":{"rendered":"Lei de Fintech: principais desafios para 2025"},"content":{"rendered":"\n<p><span data-contrast=\"auto\">O Chile \u00e9 um dos poucos pa\u00edses da Am\u00e9rica Latina que, devido \u00e0 maturidade de seu mercado, tem uma Lei de Fintech para regular a atividade dos provedores de servi\u00e7os financeiros e tecnol\u00f3gicos. Essa legisla\u00e7\u00e3o foi necess\u00e1ria para estabelecer as bases para uma maior inova\u00e7\u00e3o e concorr\u00eancia no setor financeiro, oferecendo uma estrutura regulat\u00f3ria para o desenvolvimento de servi\u00e7os financeiros baseados em tecnologia e inova\u00e7\u00e3o.\u00a0 Embora as fintechs operassem com graus variados de qualidade, havia tamb\u00e9m a necessidade de maior supervis\u00e3o e confian\u00e7a no sistema.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Desde sua promulga\u00e7\u00e3o em janeiro de 2023, o progresso na regulamenta\u00e7\u00e3o e nos padr\u00f5es tem sido significativo, cumprindo a premissa de n\u00e3o obstruir o crescimento de um setor que precisa continuar a se desenvolver. Isso facilitou a promo\u00e7\u00e3o de um ambiente potencialmente mais sim\u00e9trico entre as fintechs e o setor financeiro tradicional, al\u00e9m de favorecer a cria\u00e7\u00e3o de produtos e servi\u00e7os para mais consumidores e PMEs chilenos.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">No entanto, os frutos dessa regulamenta\u00e7\u00e3o ainda n\u00e3o s\u00e3o claramente vis\u00edveis. A intera\u00e7\u00e3o com os agentes estabelecidos melhorou at\u00e9 agora, mas precisamos avan\u00e7ar mais rapidamente em quest\u00f5es importantes para obter resultados. O credenciamento de processadores de dados e originadores de transa\u00e7\u00f5es de pagamento est\u00e1 pendente, e precisamos finalizar os mandatos de consentimento.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Em 2025, \u00e9 fundamental avan\u00e7ar rapidamente na defini\u00e7\u00e3o das principais entidades, como originadores de pagamentos e entidades de <\/span><a href=\"https:\/\/evertectrends.com\/processamento-de-pagamentos-e-a-experiencia-do-consumidor\/\"><span data-contrast=\"none\">processamento<\/span><\/a><span data-contrast=\"auto\"> e fornecimento de dados, todas essenciais para o avan\u00e7o. \u00c9 nesse ponto que a defini\u00e7\u00e3o \u00e9 mais urgentemente necess\u00e1ria em compara\u00e7\u00e3o com outros aspectos da legisla\u00e7\u00e3o.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Enquanto isso, no lado das fintechs, \u00e9 importante que elas trabalhem para cumprir adequadamente todos os requisitos da lei a fim de poderem se expandir conforme o esperado. O que \u00e9 not\u00e1vel nesse cen\u00e1rio \u00e9 que h\u00e1 algumas que est\u00e3o \u00e0 frente da maioria.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Hoje, o Chile \u00e9 o pa\u00eds com o maior n\u00famero de fintechs por 10.000 habitantes na Am\u00e9rica Latina, o que representa um grande alcance. O desafio \u00e9 criar as condi\u00e7\u00f5es para que uma porcentagem relevante se desenvolva em um mercado adequado, ganhe escala e atinja mais mercados na regi\u00e3o.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">A Lei de Fintech, sem d\u00favida, lan\u00e7ou as bases para um sistema financeiro mais din\u00e2mico e inclusivo, mas seu sucesso depender\u00e1 da implementa\u00e7\u00e3o efetiva das regulamenta\u00e7\u00f5es, do fortalecimento da <\/span><a href=\"https:\/\/evertectrends.com\/ciberseguranca-no-setor-bancario\/\"><span data-contrast=\"none\">seguran\u00e7a cibern\u00e9tica<\/span><\/a><span data-contrast=\"auto\">, da garantia de inclus\u00e3o financeira real e da prote\u00e7\u00e3o dos consumidores. Portanto, no pr\u00f3ximo ano, \u00e9 priorit\u00e1rio fazer um esfor\u00e7o coordenado entre os reguladores, o setor e a sociedade civil para progredir rapidamente na consolida\u00e7\u00e3o de um ecossistema financeiro robusto e equitativo.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":34,"featured_media":55163,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[997],"tags":[1140,1253,2420,1254,1255,373,161,538],"class_list":["post-55141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regulamentacao","tag-america-latina","tag-chile","tag-evertec-pt-br","tag-evertec-inc","tag-lei-de-fintech","tag-pagamentos","tag-regulamentacao","tag-sinqia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lei de Fintech: principais desafios para 2025 - Evertec Trends<\/title>\n<meta name=\"description\" content=\"Entenda os principais desafios da Lei de Fintech para 2025 no Chile - um dos poucos pa\u00edses da Am\u00e9rica Latina que tem uma lei desse tipo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lei de Fintech: principais desafios para 2025 - Evertec Trends\" \/>\n<meta property=\"og:description\" content=\"Entenda os principais desafios da Lei de Fintech para 2025 no Chile - um dos poucos pa\u00edses da Am\u00e9rica Latina que tem uma lei desse tipo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Evertec Trends\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-29T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-19T14:47:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/evertectrends.dev.creativetm.co\/wp-content\/uploads\/2025\/03\/fintech_principais_desafios-100.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1281\" \/>\n\t<meta property=\"og:image:height\" content=\"721\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pablo Huircapan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pablo Huircapan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/\"},\"author\":{\"name\":\"Pablo Huircapan\",\"@id\":\"https:\/\/evertectrends.com\/#\/schema\/person\/6ed81e9e0beb5d0df6ade98f4e677489\"},\"headline\":\"Lei de Fintech: principais desafios para 2025\",\"datePublished\":\"2025-01-29T10:00:00+00:00\",\"dateModified\":\"2025-08-19T14:47:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/\"},\"wordCount\":465,\"publisher\":{\"@id\":\"https:\/\/evertectrends.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2025\/03\/fintech_principais_desafios-100.jpg\",\"keywords\":[\"Am\u00e9rica Latina\",\"Chile\",\"Evertec\",\"Evertec Inc\",\"lei de fintech\",\"Pagamentos\",\"regulamenta\u00e7\u00e3o\",\"sinqia\"],\"articleSection\":[\"Regulamenta\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/\",\"url\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/\",\"name\":\"Lei de Fintech: principais desafios para 2025 - Evertec Trends\",\"isPartOf\":{\"@id\":\"https:\/\/evertectrends.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2025\/03\/fintech_principais_desafios-100.jpg\",\"datePublished\":\"2025-01-29T10:00:00+00:00\",\"dateModified\":\"2025-08-19T14:47:28+00:00\",\"description\":\"Entenda os principais desafios da Lei de Fintech para 2025 no Chile - um dos poucos pa\u00edses da Am\u00e9rica Latina que tem uma lei desse tipo.\",\"breadcrumb\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/#primaryimage\",\"url\":\"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2025\/03\/fintech_principais_desafios-100.jpg\",\"contentUrl\":\"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2025\/03\/fintech_principais_desafios-100.jpg\",\"width\":1281,\"height\":721,\"caption\":\"lei-de-fintech-principais-desafios-para-2025\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/evertectrends.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Regulamenta\u00e7\u00e3o\",\"item\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/categoria\/regulamentacao\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lei de Fintech: principais desafios para 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/evertectrends.com\/#website\",\"url\":\"https:\/\/evertectrends.com\/\",\"name\":\"Evertec Trends\",\"description\":\"As tend\u00eancias de tecnologia para inovar com estrat\u00e9gia\",\"publisher\":{\"@id\":\"https:\/\/evertectrends.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/evertectrends.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/evertectrends.com\/#organization\",\"name\":\"Evertec Trends\",\"url\":\"https:\/\/evertectrends.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/evertectrends.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2024\/03\/logotipo-evertec-trends.svg\",\"contentUrl\":\"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2024\/03\/logotipo-evertec-trends.svg\",\"width\":241,\"height\":29,\"caption\":\"Evertec Trends\"},\"image\":{\"@id\":\"https:\/\/evertectrends.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/evertectrends.com\/#\/schema\/person\/6ed81e9e0beb5d0df6ade98f4e677489\",\"name\":\"Pablo Huircapan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/evertectrends.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/56d7321070ed20e4b84a703b0c3e59c1564f42e463c7c6fb111ba8c74a824d94?s=96&d=robohash&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/56d7321070ed20e4b84a703b0c3e59c1564f42e463c7c6fb111ba8c74a824d94?s=96&d=robohash&r=g\",\"caption\":\"Pablo Huircapan\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/pablo-huircapan-becerra-0334164b\/\"],\"url\":\"https:\/\/evertectrends.com\/pt-br\/author\/pablo-huircapan\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lei de Fintech: principais desafios para 2025 - Evertec Trends","description":"Entenda os principais desafios da Lei de Fintech para 2025 no Chile - um dos poucos pa\u00edses da Am\u00e9rica Latina que tem uma lei desse tipo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/","og_locale":"pt_BR","og_type":"article","og_title":"Lei de Fintech: principais desafios para 2025 - Evertec Trends","og_description":"Entenda os principais desafios da Lei de Fintech para 2025 no Chile - um dos poucos pa\u00edses da Am\u00e9rica Latina que tem uma lei desse tipo.","og_url":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/","og_site_name":"Evertec Trends","article_published_time":"2025-01-29T10:00:00+00:00","article_modified_time":"2025-08-19T14:47:28+00:00","og_image":[{"width":1281,"height":721,"url":"https:\/\/evertectrends.dev.creativetm.co\/wp-content\/uploads\/2025\/03\/fintech_principais_desafios-100.jpg","type":"image\/jpeg"}],"author":"Pablo Huircapan","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Pablo Huircapan","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/#article","isPartOf":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/"},"author":{"name":"Pablo Huircapan","@id":"https:\/\/evertectrends.com\/#\/schema\/person\/6ed81e9e0beb5d0df6ade98f4e677489"},"headline":"Lei de Fintech: principais desafios para 2025","datePublished":"2025-01-29T10:00:00+00:00","dateModified":"2025-08-19T14:47:28+00:00","mainEntityOfPage":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/"},"wordCount":465,"publisher":{"@id":"https:\/\/evertectrends.com\/#organization"},"image":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2025\/03\/fintech_principais_desafios-100.jpg","keywords":["Am\u00e9rica Latina","Chile","Evertec","Evertec Inc","lei de fintech","Pagamentos","regulamenta\u00e7\u00e3o","sinqia"],"articleSection":["Regulamenta\u00e7\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/","url":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/","name":"Lei de Fintech: principais desafios para 2025 - Evertec Trends","isPartOf":{"@id":"https:\/\/evertectrends.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/#primaryimage"},"image":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2025\/03\/fintech_principais_desafios-100.jpg","datePublished":"2025-01-29T10:00:00+00:00","dateModified":"2025-08-19T14:47:28+00:00","description":"Entenda os principais desafios da Lei de Fintech para 2025 no Chile - um dos poucos pa\u00edses da Am\u00e9rica Latina que tem uma lei desse tipo.","breadcrumb":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/evertectrends.dev.creativetm.co\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/#primaryimage","url":"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2025\/03\/fintech_principais_desafios-100.jpg","contentUrl":"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2025\/03\/fintech_principais_desafios-100.jpg","width":1281,"height":721,"caption":"lei-de-fintech-principais-desafios-para-2025"},{"@type":"BreadcrumbList","@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/lei-de-fintech-principais-desafios-para-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/evertectrends.com\/"},{"@type":"ListItem","position":2,"name":"Regulamenta\u00e7\u00e3o","item":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/categoria\/regulamentacao\/"},{"@type":"ListItem","position":3,"name":"Lei de Fintech: principais desafios para 2025"}]},{"@type":"WebSite","@id":"https:\/\/evertectrends.com\/#website","url":"https:\/\/evertectrends.com\/","name":"Evertec Trends","description":"As tend\u00eancias de tecnologia para inovar com estrat\u00e9gia","publisher":{"@id":"https:\/\/evertectrends.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/evertectrends.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/evertectrends.com\/#organization","name":"Evertec Trends","url":"https:\/\/evertectrends.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/evertectrends.com\/#\/schema\/logo\/image\/","url":"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2024\/03\/logotipo-evertec-trends.svg","contentUrl":"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2024\/03\/logotipo-evertec-trends.svg","width":241,"height":29,"caption":"Evertec Trends"},"image":{"@id":"https:\/\/evertectrends.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/evertectrends.com\/#\/schema\/person\/6ed81e9e0beb5d0df6ade98f4e677489","name":"Pablo Huircapan","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/evertectrends.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/56d7321070ed20e4b84a703b0c3e59c1564f42e463c7c6fb111ba8c74a824d94?s=96&d=robohash&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56d7321070ed20e4b84a703b0c3e59c1564f42e463c7c6fb111ba8c74a824d94?s=96&d=robohash&r=g","caption":"Pablo Huircapan"},"sameAs":["https:\/\/www.linkedin.com\/in\/pablo-huircapan-becerra-0334164b\/"],"url":"https:\/\/evertectrends.com\/pt-br\/author\/pablo-huircapan\/"}]}},"featured_image_url":"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2025\/03\/fintech_principais_desafios-100.jpg","primary_category":"Regulamenta\u00e7\u00e3o","_links":{"self":[{"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/posts\/55141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/comments?post=55141"}],"version-history":[{"count":0,"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/posts\/55141\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/media\/55163"}],"wp:attachment":[{"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/media?parent=55141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/categories?post=55141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/tags?post=55141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}