{"id":4879,"date":"2022-04-27T14:39:48","date_gmt":"2022-04-27T17:39:48","guid":{"rendered":"https:\/\/sinqia.com.br\/?p=4879"},"modified":"2025-08-19T11:01:25","modified_gmt":"2025-08-19T14:01:25","slug":"conheca-a-historia-de-inovacao-da-sinqia-e-saiba-mais-sobre-as-solucoes-que-podem-tornar-o-seu-negocio-mais-eficiente","status":"publish","type":"post","link":"https:\/\/evertectrends.com\/pt-br\/conheca-a-historia-de-inovacao-da-sinqia-e-saiba-mais-sobre-as-solucoes-que-podem-tornar-o-seu-negocio-mais-eficiente\/","title":{"rendered":"Conhe\u00e7a a hist\u00f3ria de inova\u00e7\u00e3o da Sinqia e saiba mais sobre as solu\u00e7\u00f5es que podem tornar o seu neg\u00f3cio mais eficiente"},"content":{"rendered":"\n<p><em>Ao longo dos mais de 25 anos de trajet\u00f3ria, a Sinqia auxilia empresas durante as etapas de obten\u00e7\u00e3o de licen\u00e7as junto aos \u00f3rg\u00e3os reguladores \u00e0 reinven\u00e7\u00e3o de portf\u00f3lio e experi\u00eancias dos clientes.<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Para manter-se atualizado frente \u00e0s inova\u00e7\u00f5es, \u00e9 preciso contar com o aux\u00edlio de parceiros que tenham tradi\u00e7\u00e3o e cases de sucesso nesse mercado. A Sinqia, l\u00edder em tecnologia para o mercado financeiro, \u00e9 esse parceiro.<\/p>\n\n\n\n<p>Com mais de 25 anos no mercado, a Sinqia acompanha e faz parte das in\u00fameras transforma\u00e7\u00f5es do mercado financeiro. Fundada em 1996 como S\u00eanior Solution, a empresa fez 23 aquisi\u00e7\u00f5es ao longo da sua trajet\u00f3ria, sendo as mais recentes a compra da <a href=\"https:\/\/sinqia.com.br\/2021\/12\/22\/sinqia-compra-newcon-e-fortalece-posicionamento-de-lideranca-em-softwares-para-o-sistema-financeiro\/\">NewCon<\/a> e o controle da <a href=\"https:\/\/sinqia.com.br\/2022\/01\/18\/sinqia-adquire-controle-da-lote45\/\">LOTE45<\/a>.<\/p>\n\n\n\n<p>Desde a estabiliza\u00e7\u00e3o do real e da economia brasileira, \u00e0 abertura do mercado com a flexibiliza\u00e7\u00e3o do BACEN para abertura de novas institui\u00e7\u00f5es, passando pelo surgimento das Fintechs, Bancos Digitais, PIX, LGPD e com a mais recente demanda do mercado, o Open Banking.<\/p>\n\n\n\n<p>Ap\u00f3s a fase de hiperinfla\u00e7\u00e3o, as ind\u00fastrias buscavam novas fontes de financiamento para angariar recursos e alavancar o crescimento do seu neg\u00f3cio principal, e, parceiros que financiassem seus clientes.<\/p>\n\n\n\n<p>Desta maneira, essas ind\u00fastrias dependiam das institui\u00e7\u00f5es financeiras tradicionais para obter recursos para investimentos e principalmente, para financiar o bem de consumo produzido para o seu cliente final.<\/p>\n\n\n\n<p>Esse cen\u00e1rio levou o Banco Central adotar estrat\u00e9gias para ampliar o mercado financeiro e para isso, era preciso flexibilizar as regras para a abertura de institui\u00e7\u00f5es financeiras.<\/p>\n\n\n\n<p>Neste momento, as ind\u00fastrias come\u00e7aram a consumir o servi\u00e7o de consultoria especializada no mercado financeiro para auxiliar no processo junto ao Banco Central.<\/p>\n\n\n\n<p>Foi nessa \u00e9poca que surgiu a Controlbanc, uma empresa de consultoria brasileira especialista no mercado financeiro.&nbsp; Sua atua\u00e7\u00e3o consistia em validar o modelo de neg\u00f3cio pretendido pelo cliente, atrav\u00e9s de Estudo de Viabilidade. Ap\u00f3s a comprova\u00e7\u00e3o da viabilidade a Controlbanc auxiliava no pedido de autoriza\u00e7\u00e3o no Bacen e depois de aprovado, orientava na estrutura\u00e7\u00e3o operacional da nova institui\u00e7\u00e3o financeira.<\/p>\n\n\n\n<p>Com essa especialidade a Controlbanc se consolidou no mercado de consultoria para o mercado financeiro e passou a ganhar destaque com um modelo de projeto eficiente e com a expertise nos tr\u00e2mites exigidos pelos \u00f3rg\u00e3os reguladores.<\/p>\n\n\n\n<p>Ao longo dos anos foram mais de 150 institui\u00e7\u00f5es autorizadas e mais de 60 opera\u00e7\u00f5es em regime \u201cturn-the-key\u201d.<\/p>\n\n\n\n<p>Em 2010, a Sinqia adquiriu a Controlbanc, pois enxergou na empresa e em seus colaboradores um conhecimento t\u00e9cnico e mercadol\u00f3gico muito grande e que faria muito sentido para as estrat\u00e9gias daquele momento.<\/p>\n\n\n\n<p><em>Leia tamb\u00e9m:<\/em><\/p>\n\n\n\n<p><a href=\"https:\/\/sinqia.com.br\/2021\/12\/01\/saiba-como-a-sinqia-pode-ajudar-a-tirar-do-papel-a-sua-proxima-solucao\/\">Saiba como a Sinqia pode ajudar a tirar do papel a sua pr\u00f3xima solu\u00e7\u00e3o | Sinqia<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/sinqia.com.br\/2021\/11\/17\/4-dicas-para-a-transformacao-digital-da-sua-empresa\/\">4 dicas para a transforma\u00e7\u00e3o digital da sua empresa | Sinqia<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/sinqia.com.br\/2021\/11\/29\/entenda-como-sistema-de-conciliacao-pode-ser-um-parceiro-da-sua-empresa\/\">Entenda como sistema de concilia\u00e7\u00e3o pode ser um parceiro da sua empresa | Sinqia<\/a><\/p>\n\n\n\n<p>\u201cAo longo do tempo, come\u00e7amos a criar novas compet\u00eancias, experi\u00eancias e repert\u00f3rios que nos permitiram ter uma oferta de servi\u00e7os bastante robusta, consistente, inovadora e atualizada\u201d, comenta o diretor de design de neg\u00f3cios da Sinqia, Fabio Gonsalez.<\/p>\n\n\n\n<p>A partir da fus\u00e3o, os servi\u00e7os oferecidos pela Controlbanc ao mercado foram incrementados por outras demandas que surgiram. Com a sinergia entre os softwares para o mercado financeiro oferecido pela Sinqia e os servi\u00e7os desenvolvidos pela Controlbanc.<\/p>\n\n\n\n<p>Em 2017, ap\u00f3s alguns anos desta experi\u00eancia da combina\u00e7\u00e3o entre as duas empresas, a Sinqia ampliou ainda mais seu portf\u00f3lio de servi\u00e7os e deu vida ao Torq, seu bra\u00e7o de inova\u00e7\u00e3o.<\/p>\n\n\n\n<p>O Torq nasceu em 2018 com dois principais objetivos: tirar do papel aplicativos e solu\u00e7\u00f5es que pudessem atender \u00e0s car\u00eancias de seus clientes e, aproxim\u00e1-los do p\u00fablico-alvo de forma mais assertiva na cria\u00e7\u00e3o das jornadas digitais.<\/p>\n\n\n\n<p>\u201cSe o cliente estava pensando em um produto, uma coisa nova, como um servi\u00e7o ou aplicativo, a gente entra com a parte estrat\u00e9gica, de pesquisa, desenho e prototipa\u00e7\u00e3o\u201d, comenta Gonsalez.<\/p>\n\n\n\n<p>Em 2019, a Sinqia entendeu que as ofertas tradicionais oferecidas pela Controlbanc e a oferta inovadora do Torq tinham muita sinergia e por isso deveriam estar debaixo de uma mesma estrat\u00e9gia.<\/p>\n\n\n\n<p>Um exemplo pr\u00e1tico dessa sinergia s\u00e3o projetos para lan\u00e7amento de Fintechs. O cliente na Sinqia pode encontrar desde o estudo de viabilidade, aprova\u00e7\u00e3o no Bacen, estrutura\u00e7\u00e3o operacional e, por se tratar de uma institui\u00e7\u00e3o digital, pode contratar todo servi\u00e7o para desenho e desenvolvimento das jornadas dos usu\u00e1rios, prototipa\u00e7\u00e3o, desenvolvimento de canais digitais.<\/p>\n\n\n\n<p>Al\u00e9m disto, o cliente pode contar com as solu\u00e7\u00f5es de Core Banc\u00e1rio que a Sinqia oferece para operacionalizar o BackOffice dessa nova Fintech.<\/p>\n\n\n\n<p>&#8220;Quando a gente fala de estudos de viabilidade, \u00e9 poss\u00edvel apontar tend\u00eancias no mercado, avaliar os resultados e a necessidade de investimento. As coisas acontecem de uma maneira muito mais interessante porque j\u00e1 trazem o olhar de inova\u00e7\u00e3o para atender a demanda do cliente&#8221;, explica o diretor de Design de Neg\u00f3cios da Sinqia.<\/p>\n\n\n\n<p><a href=\"https:\/\/cloud.sq.sinqia.com.br\/sinqia-unidade-servico\">Entre em contato<\/a> com nossos especialistas e saiba mais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ao longo dos mais de 25 anos de trajet\u00f3ria, a Sinqia auxilia empresas durante as etapas de obten\u00e7\u00e3o de licen\u00e7as junto aos \u00f3rg\u00e3os reguladores \u00e0 reinven\u00e7\u00e3o de portf\u00f3lio e experi\u00eancias dos clientes. Para manter-se atualizado frente \u00e0s inova\u00e7\u00f5es, \u00e9 preciso contar com o aux\u00edlio de parceiros que tenham tradi\u00e7\u00e3o e cases de sucesso nesse mercado. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":45792,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1002],"tags":[2420],"class_list":["post-4879","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos-evertec","tag-evertec-pt-br"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Conhe\u00e7a a hist\u00f3ria de inova\u00e7\u00e3o da Sinqia e saiba mais sobre as solu\u00e7\u00f5es que podem tornar o seu neg\u00f3cio mais eficiente - Evertec Trends<\/title>\n<meta name=\"description\" content=\"Ao longo dos mais de 25 anos de trajet\u00f3ria, a Sinqia auxilia empresas durante as etapas de obten\u00e7\u00e3o de licen\u00e7as junto aos \u00f3rg\u00e3os reguladores \u00e0 reinven\u00e7\u00e3o de portf\u00f3lio e experi\u00eancias dos clientes\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conhe\u00e7a a hist\u00f3ria de inova\u00e7\u00e3o da Sinqia e saiba mais sobre as solu\u00e7\u00f5es que podem tornar o seu neg\u00f3cio mais eficiente - Evertec Trends\" \/>\n<meta property=\"og:description\" content=\"Ao longo dos mais de 25 anos de trajet\u00f3ria, a Sinqia auxilia empresas durante as etapas de obten\u00e7\u00e3o de licen\u00e7as junto aos \u00f3rg\u00e3os reguladores \u00e0 reinven\u00e7\u00e3o de portf\u00f3lio e experi\u00eancias dos clientes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/conheca-a-historia-de-inovacao-da-sinqia-e-saiba-mais-sobre-as-solucoes-que-podem-tornar-o-seu-negocio-mais-eficiente\/\" \/>\n<meta property=\"og:site_name\" content=\"Evertec Trends\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-27T17:39:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-19T14:01:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/evertectrends.dev.creativetm.co\/wp-content\/uploads\/2022\/04\/COM-1-site-banner-1024x682.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Aline Pacheco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aline Pacheco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/conheca-a-historia-de-inovacao-da-sinqia-e-saiba-mais-sobre-as-solucoes-que-podem-tornar-o-seu-negocio-mais-eficiente\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/conheca-a-historia-de-inovacao-da-sinqia-e-saiba-mais-sobre-as-solucoes-que-podem-tornar-o-seu-negocio-mais-eficiente\/\"},\"author\":{\"name\":\"Aline Pacheco\",\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/#\/schema\/person\/d97d207dbbfd36466f649fa638d7a026\"},\"headline\":\"Conhe\u00e7a a hist\u00f3ria de inova\u00e7\u00e3o da Sinqia e saiba mais sobre as solu\u00e7\u00f5es que podem tornar o seu neg\u00f3cio mais eficiente\",\"datePublished\":\"2022-04-27T17:39:48+00:00\",\"dateModified\":\"2025-08-19T14:01:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/conheca-a-historia-de-inovacao-da-sinqia-e-saiba-mais-sobre-as-solucoes-que-podem-tornar-o-seu-negocio-mais-eficiente\/\"},\"wordCount\":892,\"publisher\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/#organization\"},\"image\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/conheca-a-historia-de-inovacao-da-sinqia-e-saiba-mais-sobre-as-solucoes-que-podem-tornar-o-seu-negocio-mais-eficiente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2022\/04\/COM-1-site-banner.png\",\"keywords\":[\"Evertec\"],\"articleSection\":[\"Evertec\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/conheca-a-historia-de-inovacao-da-sinqia-e-saiba-mais-sobre-as-solucoes-que-podem-tornar-o-seu-negocio-mais-eficiente\/\",\"url\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/conheca-a-historia-de-inovacao-da-sinqia-e-saiba-mais-sobre-as-solucoes-que-podem-tornar-o-seu-negocio-mais-eficiente\/\",\"name\":\"Conhe\u00e7a a hist\u00f3ria de inova\u00e7\u00e3o da Sinqia e saiba mais sobre as solu\u00e7\u00f5es que podem tornar o seu neg\u00f3cio mais eficiente - Evertec Trends\",\"isPartOf\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/conheca-a-historia-de-inovacao-da-sinqia-e-saiba-mais-sobre-as-solucoes-que-podem-tornar-o-seu-negocio-mais-eficiente\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/conheca-a-historia-de-inovacao-da-sinqia-e-saiba-mais-sobre-as-solucoes-que-podem-tornar-o-seu-negocio-mais-eficiente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2022\/04\/COM-1-site-banner.png\",\"datePublished\":\"2022-04-27T17:39:48+00:00\",\"dateModified\":\"2025-08-19T14:01:25+00:00\",\"description\":\"Ao longo dos mais de 25 anos de trajet\u00f3ria, a Sinqia auxilia empresas durante as etapas de obten\u00e7\u00e3o de licen\u00e7as junto aos \u00f3rg\u00e3os reguladores \u00e0 reinven\u00e7\u00e3o de portf\u00f3lio e experi\u00eancias dos clientes\",\"breadcrumb\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/conheca-a-historia-de-inovacao-da-sinqia-e-saiba-mais-sobre-as-solucoes-que-podem-tornar-o-seu-negocio-mais-eficiente\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/conheca-a-historia-de-inovacao-da-sinqia-e-saiba-mais-sobre-as-solucoes-que-podem-tornar-o-seu-negocio-mais-eficiente\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/conheca-a-historia-de-inovacao-da-sinqia-e-saiba-mais-sobre-as-solucoes-que-podem-tornar-o-seu-negocio-mais-eficiente\/#primaryimage\",\"url\":\"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2022\/04\/COM-1-site-banner.png\",\"contentUrl\":\"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2022\/04\/COM-1-site-banner.png\",\"width\":2000,\"height\":1333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/conheca-a-historia-de-inovacao-da-sinqia-e-saiba-mais-sobre-as-solucoes-que-podem-tornar-o-seu-negocio-mais-eficiente\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/evertectrends.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Evertec\",\"item\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/categoria\/artigos-evertec\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conhe\u00e7a a hist\u00f3ria de inova\u00e7\u00e3o da Sinqia e saiba mais sobre as solu\u00e7\u00f5es que podem tornar o seu neg\u00f3cio mais eficiente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/#website\",\"url\":\"https:\/\/evertectrends.dev.creativetm.co\/\",\"name\":\"Evertec Trends\",\"description\":\"As tend\u00eancias de tecnologia para inovar com estrat\u00e9gia\",\"publisher\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/evertectrends.dev.creativetm.co\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/#organization\",\"name\":\"Evertec Trends\",\"url\":\"https:\/\/evertectrends.dev.creativetm.co\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2024\/03\/logotipo-evertec-trends.svg\",\"contentUrl\":\"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2024\/03\/logotipo-evertec-trends.svg\",\"width\":241,\"height\":29,\"caption\":\"Evertec Trends\"},\"image\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/#\/schema\/person\/d97d207dbbfd36466f649fa638d7a026\",\"name\":\"Aline Pacheco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6af7c7866012d2d12741711f9580c492a2aabcacbaa828515f6088310a950423?s=96&d=robohash&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6af7c7866012d2d12741711f9580c492a2aabcacbaa828515f6088310a950423?s=96&d=robohash&r=g\",\"caption\":\"Aline Pacheco\"},\"sameAs\":[\"https:\/\/www.instagram.com\/\",\"https:\/\/www.linkedin.com\/in\/alinepachecosilva\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/\"],\"url\":\"https:\/\/evertectrends.com\/pt-br\/author\/aline-pacheco\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conhe\u00e7a a hist\u00f3ria de inova\u00e7\u00e3o da Sinqia e saiba mais sobre as solu\u00e7\u00f5es que podem tornar o seu neg\u00f3cio mais eficiente - Evertec Trends","description":"Ao longo dos mais de 25 anos de trajet\u00f3ria, a Sinqia auxilia empresas durante as etapas de obten\u00e7\u00e3o de licen\u00e7as junto aos \u00f3rg\u00e3os reguladores \u00e0 reinven\u00e7\u00e3o de portf\u00f3lio e experi\u00eancias dos clientes","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"Conhe\u00e7a a hist\u00f3ria de inova\u00e7\u00e3o da Sinqia e saiba mais sobre as solu\u00e7\u00f5es que podem tornar o seu neg\u00f3cio mais eficiente - Evertec Trends","og_description":"Ao longo dos mais de 25 anos de trajet\u00f3ria, a Sinqia auxilia empresas durante as etapas de obten\u00e7\u00e3o de licen\u00e7as junto aos \u00f3rg\u00e3os reguladores \u00e0 reinven\u00e7\u00e3o de portf\u00f3lio e experi\u00eancias dos clientes","og_url":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/conheca-a-historia-de-inovacao-da-sinqia-e-saiba-mais-sobre-as-solucoes-que-podem-tornar-o-seu-negocio-mais-eficiente\/","og_site_name":"Evertec Trends","article_published_time":"2022-04-27T17:39:48+00:00","article_modified_time":"2025-08-19T14:01:25+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/evertectrends.dev.creativetm.co\/wp-content\/uploads\/2022\/04\/COM-1-site-banner-1024x682.png","type":"image\/png"}],"author":"Aline Pacheco","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/","twitter_misc":{"Written by":"Aline Pacheco","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/conheca-a-historia-de-inovacao-da-sinqia-e-saiba-mais-sobre-as-solucoes-que-podem-tornar-o-seu-negocio-mais-eficiente\/#article","isPartOf":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/conheca-a-historia-de-inovacao-da-sinqia-e-saiba-mais-sobre-as-solucoes-que-podem-tornar-o-seu-negocio-mais-eficiente\/"},"author":{"name":"Aline Pacheco","@id":"https:\/\/evertectrends.dev.creativetm.co\/#\/schema\/person\/d97d207dbbfd36466f649fa638d7a026"},"headline":"Conhe\u00e7a a hist\u00f3ria de inova\u00e7\u00e3o da Sinqia e saiba mais sobre as solu\u00e7\u00f5es que podem tornar o seu neg\u00f3cio mais eficiente","datePublished":"2022-04-27T17:39:48+00:00","dateModified":"2025-08-19T14:01:25+00:00","mainEntityOfPage":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/conheca-a-historia-de-inovacao-da-sinqia-e-saiba-mais-sobre-as-solucoes-que-podem-tornar-o-seu-negocio-mais-eficiente\/"},"wordCount":892,"publisher":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/#organization"},"image":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/conheca-a-historia-de-inovacao-da-sinqia-e-saiba-mais-sobre-as-solucoes-que-podem-tornar-o-seu-negocio-mais-eficiente\/#primaryimage"},"thumbnailUrl":"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2022\/04\/COM-1-site-banner.png","keywords":["Evertec"],"articleSection":["Evertec"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/conheca-a-historia-de-inovacao-da-sinqia-e-saiba-mais-sobre-as-solucoes-que-podem-tornar-o-seu-negocio-mais-eficiente\/","url":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/conheca-a-historia-de-inovacao-da-sinqia-e-saiba-mais-sobre-as-solucoes-que-podem-tornar-o-seu-negocio-mais-eficiente\/","name":"Conhe\u00e7a a hist\u00f3ria de inova\u00e7\u00e3o da Sinqia e saiba mais sobre as solu\u00e7\u00f5es que podem tornar o seu neg\u00f3cio mais eficiente - Evertec Trends","isPartOf":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/conheca-a-historia-de-inovacao-da-sinqia-e-saiba-mais-sobre-as-solucoes-que-podem-tornar-o-seu-negocio-mais-eficiente\/#primaryimage"},"image":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/conheca-a-historia-de-inovacao-da-sinqia-e-saiba-mais-sobre-as-solucoes-que-podem-tornar-o-seu-negocio-mais-eficiente\/#primaryimage"},"thumbnailUrl":"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2022\/04\/COM-1-site-banner.png","datePublished":"2022-04-27T17:39:48+00:00","dateModified":"2025-08-19T14:01:25+00:00","description":"Ao longo dos mais de 25 anos de trajet\u00f3ria, a Sinqia auxilia empresas durante as etapas de obten\u00e7\u00e3o de licen\u00e7as junto aos \u00f3rg\u00e3os reguladores \u00e0 reinven\u00e7\u00e3o de portf\u00f3lio e experi\u00eancias dos clientes","breadcrumb":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/conheca-a-historia-de-inovacao-da-sinqia-e-saiba-mais-sobre-as-solucoes-que-podem-tornar-o-seu-negocio-mais-eficiente\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/evertectrends.dev.creativetm.co\/pt-br\/conheca-a-historia-de-inovacao-da-sinqia-e-saiba-mais-sobre-as-solucoes-que-podem-tornar-o-seu-negocio-mais-eficiente\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/conheca-a-historia-de-inovacao-da-sinqia-e-saiba-mais-sobre-as-solucoes-que-podem-tornar-o-seu-negocio-mais-eficiente\/#primaryimage","url":"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2022\/04\/COM-1-site-banner.png","contentUrl":"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2022\/04\/COM-1-site-banner.png","width":2000,"height":1333},{"@type":"BreadcrumbList","@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/conheca-a-historia-de-inovacao-da-sinqia-e-saiba-mais-sobre-as-solucoes-que-podem-tornar-o-seu-negocio-mais-eficiente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/evertectrends.com\/en\/"},{"@type":"ListItem","position":2,"name":"Evertec","item":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/categoria\/artigos-evertec\/"},{"@type":"ListItem","position":3,"name":"Conhe\u00e7a a hist\u00f3ria de inova\u00e7\u00e3o da Sinqia e saiba mais sobre as solu\u00e7\u00f5es que podem tornar o seu neg\u00f3cio mais eficiente"}]},{"@type":"WebSite","@id":"https:\/\/evertectrends.dev.creativetm.co\/#website","url":"https:\/\/evertectrends.dev.creativetm.co\/","name":"Evertec Trends","description":"As tend\u00eancias de tecnologia para inovar com estrat\u00e9gia","publisher":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/evertectrends.dev.creativetm.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/evertectrends.dev.creativetm.co\/#organization","name":"Evertec Trends","url":"https:\/\/evertectrends.dev.creativetm.co\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/evertectrends.dev.creativetm.co\/#\/schema\/logo\/image\/","url":"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2024\/03\/logotipo-evertec-trends.svg","contentUrl":"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2024\/03\/logotipo-evertec-trends.svg","width":241,"height":29,"caption":"Evertec Trends"},"image":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/evertectrends.dev.creativetm.co\/#\/schema\/person\/d97d207dbbfd36466f649fa638d7a026","name":"Aline Pacheco","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/evertectrends.dev.creativetm.co\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6af7c7866012d2d12741711f9580c492a2aabcacbaa828515f6088310a950423?s=96&d=robohash&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6af7c7866012d2d12741711f9580c492a2aabcacbaa828515f6088310a950423?s=96&d=robohash&r=g","caption":"Aline Pacheco"},"sameAs":["https:\/\/www.instagram.com\/","https:\/\/www.linkedin.com\/in\/alinepachecosilva\/","https:\/\/x.com\/https:\/\/twitter.com\/"],"url":"https:\/\/evertectrends.com\/pt-br\/author\/aline-pacheco\/"}]}},"featured_image_url":"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2022\/04\/COM-1-site-banner.png","primary_category":"Evertec","_links":{"self":[{"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/posts\/4879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/comments?post=4879"}],"version-history":[{"count":0,"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/posts\/4879\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/media\/45792"}],"wp:attachment":[{"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/categories?post=4879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/tags?post=4879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}