{"id":10096,"date":"2020-10-05T11:00:00","date_gmt":"2020-10-05T14:00:00","guid":{"rendered":"http:\/\/site.local\/?p=10096"},"modified":"2024-07-31T17:10:35","modified_gmt":"2024-07-31T20:10:35","slug":"processo-de-pld","status":"publish","type":"post","link":"https:\/\/evertectrends.com\/pt-br\/processo-de-pld\/","title":{"rendered":"Como estruturar seu processo de PLD?"},"content":{"rendered":"\n<p>Voc\u00ea sabe o que \u00e9 preciso para estruturar um <strong>processo de PLD<\/strong> completo? A preven\u00e7\u00e3o \u00e0 lavagem de dinheiro \u00e9 fundamental para que empresas atuem em conformidade com os principais regulamentos nacionais e internacionais.<\/p>\n<p>Por isso mesmo, vale a pena conhecer os principais aspectos sobre o assunto. Nesse artigo completo vamos falar sobre a lavagem de dinheiro e indicar quais s\u00e3o os principais desafios experimentados pelo setor corporativo.<\/p>\n<p>Al\u00e9m disso, mostraremos as iniciativas das empresas para lidar com as tentativas de lavagem de dinheiro. E para que voc\u00ea possa implementar um <strong>processo de PDL<\/strong> eficiente, traremos um passo a passo com todas as etapas para a sua estrutura\u00e7\u00e3o.<\/p>\n<h4>Voc\u00ea vai encontrar neste artigo:<\/h4>\n<ol>\n<li><a href=\"#o-que-e\">O que \u00e9 a lavagem de dinheiro?<\/a><\/li>\n<li><a href=\"#pld\">E a preven\u00e7\u00e3o \u00e0 lavagem de dinheiro (PLD)?<\/a><\/li>\n<li><a href=\"#desafios\">Quais s\u00e3o os desafios do setor corporativo na preven\u00e7\u00e3o \u00e0 lavagem de dinheiro?<\/a><\/li>\n<li><a href=\"#mercado\">Como o mercado tem combatido as tentativas de lavagem de dinheiro?<\/a><\/li>\n<li><a href=\"#etapas\">Etapas para estruturar o processo de PLD<\/a><\/li>\n<li><a href=\"#simply\">O background check da Simply como solu\u00e7\u00e3o para automa\u00e7\u00e3o<\/a><\/li>\n<\/ol>\n<h2><a id=\"o-que-e\"><\/a>O que \u00e9 a lavagem de dinheiro?<\/h2>\n<p>A lavagem de dinheiro ocorre quando criminosos tentam\u00a0incorporar recursos obtidos de forma il\u00edcita na economia\u00a0de um pa\u00eds. Na maioria das vezes, esse processo se d\u00e1 em <a href=\"https:\/\/evertectrends.com\/fases-da-lavagem-de-dinheiro\/\">tr\u00eas fases<\/a>, que podem acontecer simultaneamente:<\/p>\n<ul>\n<li>coloca\u00e7\u00e3o \u2013 os criminosos colocam o dinheiro no sistema econ\u00f4mico, procurando ocultar sua origem. Para isso, escolhem pa\u00edses com regras mais permissivas;<\/li>\n<li>oculta\u00e7\u00e3o \u2013 o dinheiro \u00e9 movimentado para contas an\u00f4nimas ou em nome de \u201claranjas\u201d. Ele tamb\u00e9m \u00e9 usado em empresas fict\u00edcias ou de fachada;<\/li>\n<li>integra\u00e7\u00e3o \u2013 os recursos s\u00e3o incorporados ao sistema econ\u00f4mico legitimando o dinheiro ilegal.<\/li>\n<\/ul>\n<p>No Brasil, a principal regulamenta\u00e7\u00e3o sobre o tema \u00e9 a\u00a0<a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/LEIS\/L9613.htm\">lei 9.613\/98<\/a>, que disp\u00f5e sobre os crimes de lavagem de dinheiro. A norma discrimina as a\u00e7\u00f5es de preven\u00e7\u00e3o \u00e0 lavagem de dinheiro que devem ser adotadas pelas empresas autorizadas a funcionar pelo Banco Central.<\/p>\n<h2><a id=\"pld\"><\/a>E a preven\u00e7\u00e3o \u00e0 lavagem de dinheiro (PLD)?<\/h2>\n<p>O <strong>processo de PLD<\/strong> corresponde \u00e0 preven\u00e7\u00e3o \u00e0 lavagem de dinheiro, que \u00e9 uma pr\u00e1tica criminosa, voltada para a dissimula\u00e7\u00e3o da origem il\u00edcita de bens e capitais, com a sua incorpora\u00e7\u00e3o ao mercado.<\/p>\n<p>A Preven\u00e7\u00e3o \u00e0 Lavagem de Dinheiro (PLD) surge nesse contexto, como equivalente ao Anti-Money Laundering (AML), do ingl\u00eas. Trata-se de um processo estruturado, voltado para prevenir a lavagem de capitais.<\/p>\n<p>Assim, o <strong>processo de PLD<\/strong> \u00e9 composto por diversas estrat\u00e9gias, em sintonia com as recomenda\u00e7\u00f5es e regulamentos emitidos por \u00f3rg\u00e3os especializados, como \u00e9 o caso do Conselho de Controle de Atividades Financeiras (COAF).<\/p>\n<h2><a id=\"desafios\"><\/a>Quais s\u00e3o os desafios do setor corporativo na preven\u00e7\u00e3o \u00e0 lavagem de dinheiro?<\/h2>\n<p>O avan\u00e7o tecnol\u00f3gico trouxe novos desafios aos programas de preven\u00e7\u00e3o \u00e0 lavagem de dinheiro.<\/p>\n<p>Os recursos podem ser movimentados de forma eletr\u00f4nica e com muita rapidez, exigindo que as institui\u00e7\u00f5es financeiras tenham a mesma agilidade para conseguir continuar\u00a0<a href=\"https:\/\/evertectrends.com\/tecnologia-no-compliance-e-kyc\/\">identificando e monitorando seus clientes<\/a>.<\/p>\n<p>A lei determina que elas precisam manter\u00a0registros atualizados\u00a0das opera\u00e7\u00f5es e reportar ao COAF (Conselho de Controle de Atividades Financeiras) qualquer\u00a0opera\u00e7\u00e3o suspeita\u00a0ou crime financeiro identificado.<\/p>\n<p>Pela sua pr\u00f3pria natureza, o\u00a0mercado de c\u00e2mbio\u00a0\u00e9 um dos que precisam de maior cuidado na preven\u00e7\u00e3o \u00e0 lavagem de dinheiro, j\u00e1 que \u00e9 alvo preferencial de criminosos internacionais.<\/p>\n<p>Para isso, os bancos estabelecem pol\u00edticas de preven\u00e7\u00e3o \u00e0 lavagem de dinheiro,\u00a0treinam seus funcion\u00e1rios\u00a0para identificar transa\u00e7\u00f5es suspeitas e todos s\u00e3o legalmente obrigados a relatar qualquer atividade fora dos padr\u00f5es.<\/p>\n<h2><a id=\"mercado\"><\/a>Como o mercado tem combatido as tentativas de lavagem de dinheiro?<\/h2>\n<p>Al\u00e9m do treinamento dos funcion\u00e1rios para identificar opera\u00e7\u00f5es suspeitas, as empresas t\u00eam usado a tecnologia a seu favor para combater as tentativas de lavar dinheiro. O investimento em solu\u00e7\u00f5es de\u00a0valida\u00e7\u00e3o de identidade\u00a0dos clientes \u00e9 um dos principais exemplos.<\/p>\n<p>Os\u00a0<a href=\"https:\/\/evertectrends.com\/cadastro-otimize-seu-processo-utilizando-a-tecnologia-ocr\/\">cadastros digitais<\/a>\u00a0s\u00e3o capazes de colher in\u00fameras informa\u00e7\u00f5es a respeito de quem tenta abrir uma conta online. Reconhecimento facial, consulta em fontes p\u00fablicas, instrumentos de identifica\u00e7\u00e3o do aparelho do cliente e dados de geolocaliza\u00e7\u00e3o s\u00e3o alguns exemplos de formas de assegurar a identifica\u00e7\u00e3o correta da pessoa que est\u00e1 tentando abrir a conta.<\/p>\n<p>Assim, o mercado corporativo tem o desafio de agregar cada vez mais\u00a0intelig\u00eancia aos seus processos, acompanhando a evolu\u00e7\u00e3o da tecnologia. Tamb\u00e9m \u00e9 necess\u00e1rio estar sempre em conformidade com as regulamenta\u00e7\u00f5es, que s\u00e3o atualizadas de acordo com as novidades que surgem.<\/p>\n<p>Por fim, h\u00e1 ainda o desafio de conseguir implementar na\u00a0abertura de\u00a0<a href=\"https:\/\/evertectrends.com\/desafios-da-conta-digital-pj-e-como-superar\/\">contas de pessoas jur\u00eddicas<\/a>\u00a0o mesmo n\u00edvel de seguran\u00e7a estabelecido para pessoas f\u00edsicas.<\/p>\n<h2><a id=\"etapas\"><\/a>Etapas para estruturar o processo de PLD<\/h2>\n<p>A estrutura\u00e7\u00e3o do <strong>processo de PLD<\/strong> deve ser feita de acordo com algumas etapas. Dessa forma \u00e9 poss\u00edvel garantir a efetividade do processo, gerando como resultados a preven\u00e7\u00e3o \u00e0 lavagem de dinheiro e a conformidade com os <a href=\"https:\/\/evertectrends.com\/regulamentacoes-do-mercado-bancario\/\">regulamentos<\/a>. Confira as etapas a seguir:<\/p>\n<h4>1- Planejamento e registro de tudo<\/h4>\n<p>Ao come\u00e7ar a estruturar o <strong>processo de PLD<\/strong>, \u00e9 importante planejar todos os seus aspectos, mantendo registros confi\u00e1veis a respeito. Os dados devem ser organizados de forma clara e acess\u00edvel.<\/p>\n<p>Durante o planejamento vale a pena estabelecer quais ser\u00e3o os planos de a\u00e7\u00e3o em caso de que alguma irregularidade seja identificada. Assim \u00e9 poss\u00edvel implementar um processo eficiente.<\/p>\n<h4>2- Conscientiza\u00e7\u00e3o dos colaboradores<\/h4>\n<p>O ambiente corporativo deve estar preparado para o <strong>processo de PLD<\/strong>. Afinal de contas, todos os agentes da empresa podem ser vetores para o cometimento de irregularidades.<\/p>\n<p>Uma equipe especializada em compliance deve ser formada, para lidar diretamente com o processo de preven\u00e7\u00e3o \u00e0 lavagem de dinheiro. O seu papel inclui o treinamento e de funcion\u00e1rios e implementa\u00e7\u00e3o de a\u00e7\u00f5es para a conscientiza\u00e7\u00e3o interna.<\/p>\n<h4>3- Defini\u00e7\u00e3o dos sinais de alerta<\/h4>\n<p>A lavagem de dinheiro acontece de forma silenciosa e muito bem organizada. Isso obriga as empresas a definirem sinais de alerta, que servir\u00e3o como ind\u00edcios de que algo est\u00e1 sendo feito em desconformidade com os regulamentos.<\/p>\n<p>Alguns exemplos s\u00e3o transa\u00e7\u00f5es de alto valor, especialmente em dinheiro vivo, frequ\u00eancia elevada de transa\u00e7\u00f5es em um curto espa\u00e7o de tempo, transa\u00e7\u00f5es realizadas a <a href=\"https:\/\/evertectrends.com\/peps-e-o-kyc\/\">pessoas politicamente expostas<\/a> e similares.<\/p>\n<p>O Banco Central exerce um papel importante nesse sentido. Ele regulamenta, monitora e fiscaliza o Sistema Financeiro Nacional (SFN). Assim, quando percebe ind\u00edcios de crimes, a institui\u00e7\u00e3o notifica o Conselho de Controle de Atividades Financeiras (COAF), Minist\u00e9rio P\u00fablico e outros \u00f3rg\u00e3os interessados.<\/p>\n<h4>4- Automatiza\u00e7\u00e3o das consultas<\/h4>\n<p>A \u00faltima etapa da estrutura\u00e7\u00e3o do <strong>processo de PLD<\/strong> \u00e9 a <a href=\"https:\/\/evertectrends.com\/background-check\/\">automatiza\u00e7\u00e3o das consultas<\/a>. Como as tentativas de fraudes podem ser feitas a qualquer momento e de diversas maneiras, \u00e9 fundamental que a empresa conte com um sistema de consulta automatizado.<\/p>\n<p>Os processos de background check e <a href=\"https:\/\/evertectrends.com\/o-que-e-know-your-customer-kyc-e-sua-importancia\/\">KYC<\/a> s\u00e3o exemplos de estrat\u00e9gias que podem ser empregadas para garantir uma checagem de qualidade e a todo o tempo. Assim \u00e9 poss\u00edvel reduzir as chances de que crimes sejam cometidos.<\/p>\n<h3>PLD e o compliance<\/h3>\n<p>O <a href=\"https:\/\/evertectrends.com\/compliance-entenda-seu-papel-em-meio-a-transformacao-digital\/\">compliance<\/a> \u00e9 o conjunto de estrat\u00e9gias voltadas para a garantia de conformidade da empresa com os regulamentos pertinentes, que tutelam a sua atua\u00e7\u00e3o no mercado. Assim, o conceito est\u00e1 diretamente relacionado com o <strong>processo de PLD<\/strong>.<\/p>\n<p>Assim, para estar em compliance com os regulamentos que tratam da preven\u00e7\u00e3o \u00e0 lavagem de dinheiro, a empresa deve implementar estrat\u00e9gias diversas, como por exemplo a dissemina\u00e7\u00e3o de uma cultura interna de preven\u00e7\u00e3o.<\/p>\n<h2><a id=\"simply\"><\/a>O background check da Simply como solu\u00e7\u00e3o para automa\u00e7\u00e3o<\/h2>\n<p>A Simply oferece produtos e solu\u00e7\u00f5es alinhadas com o processo de PLD. Trata-se de uma plataforma com ferramentas voltadas para o cadastro, formaliza\u00e7\u00e3o e onboarding digital.<\/p>\n<p>Entre as solu\u00e7\u00f5es dispon\u00edveis est\u00e1 o <a href=\"https:\/\/simply.com.br\/analise-eletronica-documentos-atomics\/\">Atomics<\/a>, respons\u00e1vel pelo reconhecimento e a extra\u00e7\u00e3o de dados de documentos, o <a href=\"https:\/\/simply.com.br\/data-mining-mineracao-de-dados\/\">Mining<\/a>, que automatiza a consulta a dados de clientes e o <a href=\"https:\/\/simply.com.br\/validador-de-rg-antifraude\/\">VAR<\/a>, ferramenta para a valida\u00e7\u00e3o autom\u00e1tica de regras antifraude para RG. Dessa forma, a Simply oferece uma <strong>Automa\u00e7\u00e3o de Consultas de Preven\u00e7\u00e3o \u00e0 Lavagem de Dinheiro<\/strong>, de forma completa e eficiente.<\/p>\n<p>O <a href=\"https:\/\/evertectrends.com\/background-check-e-o-compliance\/\">background check<\/a> \u00e9 fundamental para que riscos sejam prevenidos, incluindo os incidentes relacionados \u00e0 lavagem de dinheiro. Ele permite identificar problemas de ordem comercial, financeira, legal e criminal, com agilidade e de forma automatizada. Assim \u00e9 poss\u00edvel alinhar o processo de PLD e o compliance empresarial.<\/p>\n<p>Agende uma\u00a0<u><a href=\"https:\/\/simply.com.br\/contato\/\">demonstra\u00e7\u00e3o<\/a><\/u>\u00a0com nossos consultores e comece seu processo de background check com seguran\u00e7a e reduza custos operacionais necess\u00e1rios diante momentos de crises.<\/p>\n<p>Gostou desse conte\u00fado? Assine nossa\u00a0<a href=\"https:\/\/materiais.simply.com.br\/opt-in-newsletter\/\">newsletter<\/a>\u00a0e receba semanalmente em seu e-mail novidades da era da Transforma\u00e7\u00e3o Digital!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entenda o que \u00e9 a lavagem de dinheiro, seus principais desafios e as etapas para implementar um processo de PLD eficiente.<\/p>\n","protected":false},"author":9,"featured_media":10097,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[997,1001],"tags":[62,157,160,152,161],"class_list":["post-10096","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regulamentacao","category-seguranca","tag-compliance","tag-lavagem-de-dinheiro","tag-pld","tag-prevencao-a-lavagem-de-dinheiro","tag-regulamentacao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Como estruturar seu processo de PLD? - Evertec Trends<\/title>\n<meta name=\"description\" content=\"Entenda o que \u00e9 a lavagem de dinheiro, seus principais desafios e as etapas para implementar um processo de PLD eficiente.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como estruturar seu processo de PLD? - Evertec Trends\" \/>\n<meta property=\"og:description\" content=\"Entenda o que \u00e9 a lavagem de dinheiro, seus principais desafios e as etapas para implementar um processo de PLD eficiente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/processo-de-pld\/\" \/>\n<meta property=\"og:site_name\" content=\"Evertec Trends\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-05T14:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-31T20:10:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/evertectrends.dev.creativetm.co\/wp-content\/uploads\/2020\/09\/processo-de-pld.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"430\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Evertec Trends\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Evertec Trends\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/processo-de-pld\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/processo-de-pld\/\"},\"author\":{\"name\":\"Evertec Trends\",\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/#\/schema\/person\/e1ebcb37c3e82c62bf694bb1eca91f4d\"},\"headline\":\"Como estruturar seu processo de PLD?\",\"datePublished\":\"2020-10-05T14:00:00+00:00\",\"dateModified\":\"2024-07-31T20:10:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/processo-de-pld\/\"},\"wordCount\":1466,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/#organization\"},\"image\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/processo-de-pld\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2020\/09\/processo-de-pld.jpg\",\"keywords\":[\"Compliance\",\"lavagem de dinheiro\",\"PLD\",\"preven\u00e7\u00e3o \u00e0 lavagem de dinheiro\",\"regulamenta\u00e7\u00e3o\"],\"articleSection\":[\"Regulamenta\u00e7\u00e3o\",\"Seguran\u00e7a\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/processo-de-pld\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/processo-de-pld\/\",\"url\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/processo-de-pld\/\",\"name\":\"Como estruturar seu processo de PLD? - Evertec Trends\",\"isPartOf\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/processo-de-pld\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/processo-de-pld\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2020\/09\/processo-de-pld.jpg\",\"datePublished\":\"2020-10-05T14:00:00+00:00\",\"dateModified\":\"2024-07-31T20:10:35+00:00\",\"description\":\"Entenda o que \u00e9 a lavagem de dinheiro, seus principais desafios e as etapas para implementar um processo de PLD eficiente.\",\"breadcrumb\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/processo-de-pld\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/processo-de-pld\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/processo-de-pld\/#primaryimage\",\"url\":\"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2020\/09\/processo-de-pld.jpg\",\"contentUrl\":\"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2020\/09\/processo-de-pld.jpg\",\"width\":900,\"height\":430,\"caption\":\"processo-de-pld\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/processo-de-pld\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/evertectrends.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Regulamenta\u00e7\u00e3o\",\"item\":\"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/categoria\/regulamentacao\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Como estruturar seu processo de PLD?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/#website\",\"url\":\"https:\/\/evertectrends.dev.creativetm.co\/\",\"name\":\"Evertec Trends\",\"description\":\"As tend\u00eancias de tecnologia para inovar com estrat\u00e9gia\",\"publisher\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/evertectrends.dev.creativetm.co\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/#organization\",\"name\":\"Evertec Trends\",\"url\":\"https:\/\/evertectrends.dev.creativetm.co\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2024\/03\/logotipo-evertec-trends.svg\",\"contentUrl\":\"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2024\/03\/logotipo-evertec-trends.svg\",\"width\":241,\"height\":29,\"caption\":\"Evertec Trends\"},\"image\":{\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/#\/schema\/person\/e1ebcb37c3e82c62bf694bb1eca91f4d\",\"name\":\"Evertec Trends\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/evertectrends.dev.creativetm.co\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f46217c56c100deb166f67953efa3f81077701bca98a102e48544095d631803d?s=96&d=robohash&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f46217c56c100deb166f67953efa3f81077701bca98a102e48544095d631803d?s=96&d=robohash&r=g\",\"caption\":\"Evertec Trends\"},\"description\":\"Mais que um portal de conte\u00fados, um ponto de encontro para quem quer desvendar o setor financeiro.\",\"sameAs\":[\"https:\/\/www.instagram.com\/evertecinc\",\"https:\/\/www.linkedin.com\/company\/evertec\/\"],\"url\":\"https:\/\/evertectrends.com\/pt-br\/author\/evertectrends\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como estruturar seu processo de PLD? - Evertec Trends","description":"Entenda o que \u00e9 a lavagem de dinheiro, seus principais desafios e as etapas para implementar um processo de PLD eficiente.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"Como estruturar seu processo de PLD? - Evertec Trends","og_description":"Entenda o que \u00e9 a lavagem de dinheiro, seus principais desafios e as etapas para implementar um processo de PLD eficiente.","og_url":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/processo-de-pld\/","og_site_name":"Evertec Trends","article_published_time":"2020-10-05T14:00:00+00:00","article_modified_time":"2024-07-31T20:10:35+00:00","og_image":[{"width":900,"height":430,"url":"https:\/\/evertectrends.dev.creativetm.co\/wp-content\/uploads\/2020\/09\/processo-de-pld.jpg","type":"image\/jpeg"}],"author":"Evertec Trends","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Evertec Trends","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/processo-de-pld\/#article","isPartOf":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/processo-de-pld\/"},"author":{"name":"Evertec Trends","@id":"https:\/\/evertectrends.dev.creativetm.co\/#\/schema\/person\/e1ebcb37c3e82c62bf694bb1eca91f4d"},"headline":"Como estruturar seu processo de PLD?","datePublished":"2020-10-05T14:00:00+00:00","dateModified":"2024-07-31T20:10:35+00:00","mainEntityOfPage":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/processo-de-pld\/"},"wordCount":1466,"commentCount":0,"publisher":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/#organization"},"image":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/processo-de-pld\/#primaryimage"},"thumbnailUrl":"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2020\/09\/processo-de-pld.jpg","keywords":["Compliance","lavagem de dinheiro","PLD","preven\u00e7\u00e3o \u00e0 lavagem de dinheiro","regulamenta\u00e7\u00e3o"],"articleSection":["Regulamenta\u00e7\u00e3o","Seguran\u00e7a"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/evertectrends.dev.creativetm.co\/pt-br\/processo-de-pld\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/processo-de-pld\/","url":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/processo-de-pld\/","name":"Como estruturar seu processo de PLD? - Evertec Trends","isPartOf":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/processo-de-pld\/#primaryimage"},"image":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/processo-de-pld\/#primaryimage"},"thumbnailUrl":"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2020\/09\/processo-de-pld.jpg","datePublished":"2020-10-05T14:00:00+00:00","dateModified":"2024-07-31T20:10:35+00:00","description":"Entenda o que \u00e9 a lavagem de dinheiro, seus principais desafios e as etapas para implementar um processo de PLD eficiente.","breadcrumb":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/processo-de-pld\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/evertectrends.dev.creativetm.co\/pt-br\/processo-de-pld\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/processo-de-pld\/#primaryimage","url":"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2020\/09\/processo-de-pld.jpg","contentUrl":"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2020\/09\/processo-de-pld.jpg","width":900,"height":430,"caption":"processo-de-pld"},{"@type":"BreadcrumbList","@id":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/processo-de-pld\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/evertectrends.com\/en\/"},{"@type":"ListItem","position":2,"name":"Regulamenta\u00e7\u00e3o","item":"https:\/\/evertectrends.dev.creativetm.co\/pt-br\/categoria\/regulamentacao\/"},{"@type":"ListItem","position":3,"name":"Como estruturar seu processo de PLD?"}]},{"@type":"WebSite","@id":"https:\/\/evertectrends.dev.creativetm.co\/#website","url":"https:\/\/evertectrends.dev.creativetm.co\/","name":"Evertec Trends","description":"As tend\u00eancias de tecnologia para inovar com estrat\u00e9gia","publisher":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/evertectrends.dev.creativetm.co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/evertectrends.dev.creativetm.co\/#organization","name":"Evertec Trends","url":"https:\/\/evertectrends.dev.creativetm.co\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/evertectrends.dev.creativetm.co\/#\/schema\/logo\/image\/","url":"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2024\/03\/logotipo-evertec-trends.svg","contentUrl":"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2024\/03\/logotipo-evertec-trends.svg","width":241,"height":29,"caption":"Evertec Trends"},"image":{"@id":"https:\/\/evertectrends.dev.creativetm.co\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/evertectrends.dev.creativetm.co\/#\/schema\/person\/e1ebcb37c3e82c62bf694bb1eca91f4d","name":"Evertec Trends","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/evertectrends.dev.creativetm.co\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f46217c56c100deb166f67953efa3f81077701bca98a102e48544095d631803d?s=96&d=robohash&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f46217c56c100deb166f67953efa3f81077701bca98a102e48544095d631803d?s=96&d=robohash&r=g","caption":"Evertec Trends"},"description":"Mais que um portal de conte\u00fados, um ponto de encontro para quem quer desvendar o setor financeiro.","sameAs":["https:\/\/www.instagram.com\/evertecinc","https:\/\/www.linkedin.com\/company\/evertec\/"],"url":"https:\/\/evertectrends.com\/pt-br\/author\/evertectrends\/"}]}},"featured_image_url":"https:\/\/evertectrends-com-assets.s3.amazonaws.com\/wp-content\/uploads\/2020\/09\/processo-de-pld.jpg","primary_category":"Regulamenta\u00e7\u00e3o","_links":{"self":[{"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/posts\/10096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/comments?post=10096"}],"version-history":[{"count":0,"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/posts\/10096\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/media\/10097"}],"wp:attachment":[{"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/media?parent=10096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/categories?post=10096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evertectrends.com\/pt-br\/wp-json\/wp\/v2\/tags?post=10096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}